{"id":7679,"date":"2024-05-31T09:40:01","date_gmt":"2024-05-31T09:40:01","guid":{"rendered":"http:\/\/www.fiammedelpolesine.it\/?post_type=portfolio&#038;p=7679"},"modified":"2024-05-31T13:31:54","modified_gmt":"2024-05-31T13:31:54","slug":"domenica-25-aprile-al-motoraduno-dellasparago-a-mesola","status":"publish","type":"portfolio","link":"https:\/\/www.fiammedelpolesine.it\/index.php\/portfolio-articoli\/domenica-25-aprile-al-motoraduno-dellasparago-a-mesola\/","title":{"rendered":"Domenica 25 aprile al Motoraduno dell&#8217;asparago a Mesola"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":7670,"comment_status":"closed","ping_status":"closed","template":"","tags":[],"portfolio_entries":[25],"_links":{"self":[{"href":"https:\/\/www.fiammedelpolesine.it\/index.php\/wp-json\/wp\/v2\/portfolio\/7679"}],"collection":[{"href":"https:\/\/www.fiammedelpolesine.it\/index.php\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/www.fiammedelpolesine.it\/index.php\/wp-json\/wp\/v2\/types\/portfolio"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fiammedelpolesine.it\/index.php\/wp-json\/wp\/v2\/comments?post=7679"}],"version-history":[{"count":1,"href":"https:\/\/www.fiammedelpolesine.it\/index.php\/wp-json\/wp\/v2\/portfolio\/7679\/revisions"}],"predecessor-version":[{"id":7680,"href":"https:\/\/www.fiammedelpolesine.it\/index.php\/wp-json\/wp\/v2\/portfolio\/7679\/revisions\/7680"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fiammedelpolesine.it\/index.php\/wp-json\/wp\/v2\/media\/7670"}],"wp:attachment":[{"href":"https:\/\/www.fiammedelpolesine.it\/index.php\/wp-json\/wp\/v2\/media?parent=7679"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fiammedelpolesine.it\/index.php\/wp-json\/wp\/v2\/tags?post=7679"},{"taxonomy":"portfolio_entries","embeddable":true,"href":"https:\/\/www.fiammedelpolesine.it\/index.php\/wp-json\/wp\/v2\/portfolio_entries?post=7679"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}